{"id":37653,"date":"2023-12-14T20:21:00","date_gmt":"2023-12-14T19:21:00","guid":{"rendered":"https:\/\/hijasdejesus.org\/?p=37653"},"modified":"2023-12-14T20:21:16","modified_gmt":"2023-12-14T19:21:16","slug":"el-sinodo-continua","status":"publish","type":"post","link":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/","title":{"rendered":"El S\u00ednodo contin\u00faa"},"content":{"rendered":"\n<p><strong>S\u00ednodo de la Sinodalidad<\/strong>,\u00a0con tres acentos muy significativos:\u00a0 <strong>Participaci\u00f3n, Comuni\u00f3n,\u00a0 Misi\u00f3n, <\/strong>estamos participando en un proceso que nos afecta como iglesia y para el cual hemos recibido una invitaci\u00f3n universal.<\/p>\n\n\n\n<p>Todas las personas bautizadas que nos sentimos miembros activos de la iglesia como aquellas que se sienten alejadas o incluso quienes no tienen una fe cristiana ni se sienten dentro de la iglesia cat\u00f3lica, podemos participar, es decir, <strong>dar nuestra palabra, nuestras aportaciones, nuestras sugerencias, <\/strong>en este camino que ha tenido varias etapas.<\/p>\n\n\n\n<p>Una <strong>primera ha sido la diocesana<\/strong>.\u00a0Una <strong>segunda a nivel continental<\/strong> y nos abocamos a una<strong> etapa universal<\/strong>, que es un cap\u00edtulo importante y nos abre a otro evento en octubre 2024.<\/p>\n\n\n\n<p>Est\u00e1 siendo muy significativa la participaci\u00f3n, con trabajos miy bien hechos, de grupos que consideramos en los m\u00e1rgenes de la iglesia, a quienes no hemos dejado entrar o nuestro trato ha sido con ellos de tal manera, que les hemos obligado a salir.<\/p>\n\n\n\n<p>Es una buena noticia saber que se han abierto las puertas de la iglesia y que ella<strong><em> \u201ccabemos todos, todos, todos\u201d<\/em><\/strong>, como nos dijo el Papa Francisco en la JMJ de agosto pasado.\u00a0Esos grupos deben ser<strong> re-conocidos y por tanto nombrados para ser acogidos:<\/strong>\u00a0divorciados y vueltos a casar, colectivos LGTBI+, sacerdotes secularizados, diversos n\u00facleos familiares, encarcelados, intelectuales, mujeres,\u00a0enfermos electro-sensibles\u2026<\/p>\n\n\n\n<p>Y esta acogida debe darse a todos los niveles, desde el Papa, los cardenales,\u00a0arzobispos,\u00a0obispos,\u00a0 sacerdotes,\u00a0pero tambi\u00e9n de cada persona que nos sentimos parte de la iglesia; <strong>todos en el centro,\u00a0 nadie en los m\u00e1rgenes<\/strong> y es que la persona es lo sagradamente importante.<\/p>\n\n\n\n<p>El<strong> \u00fanico referente es Jes\u00fas y su evangelio<\/strong>:\u00a0siempre acoge, perdona, incluye, se acerca, toca, va m\u00e1s all\u00e1 de la ley, todo y siempre para salvar-sanar a la persona que acude a \u00c9l. Todas llegan destruidas y todas vuelven a casa recuperadas, comenzando una etapa nueva.<strong>\u00a0Jes\u00fas siempre nos ofrece una oportunidad para cambiar ruta.<\/strong><\/p>\n\n\n\n<p>Deseamos vivamente en nuestro coraz\u00f3n que nuestra iglesia sinodal sea as\u00ed:\u00a0<strong>lugar seguro, refugio c\u00e1lido, manos que sostienen, abrazos que hacen fiesta cuando volvemos a ella.<\/strong> Pero esto no se puede hacer sin una conversi\u00f3n personal, sin acudir al Esp\u00edritu quien es capaz de cambiar nuestro coraz\u00f3n de piedra por uno de carne,<\/p>\n\n\n\n<p>Nos ayudan nuestras comunidades,<strong> no podemos vivir la fe en solitario<\/strong>, nos impulsan al compromiso y nos mantienen y alientan en la esperanza de un futuro mejor, de una iglesia m\u00e1s parecida a la que Dios sue\u00f1a.<\/p>\n\n\n\n<p>Vivimos un momento apasionante, <strong>una oportunidad hist\u00f3rica<\/strong>, no la dejemos pasar.\u00a0 So\u00f1emos en grande; ya hay brotes verdes, quiz\u00e1 nuestros ojos no est\u00e1n limpios y por eso no los vemos, pero existen y van empujando a una iglesia Pueblo de Dios, comunidad de comunidades, que ensancha el espacio de su tienda para que todos podamos entrar.<\/p>\n\n\n\n<p>Con nuestro nombre y apellido, sin t\u00edtulos, sin ropajes, sin boatos,\u00a0sin signos ininteligibles, sino <strong>cercanos a la gente que nos rodea.\u00a0<\/strong><\/p>\n\n\n\n<p>Es ahora el momento. Abramos los ojos y o\u00eddos del coraz\u00f3n. No dejemos pasar al Esp\u00edritu que est\u00e1 a nuestro lado como brisa suave, como viento que limpia y empuja.\u00a0<strong>Podremos ser as\u00ed la iglesia de Jes\u00fas, <\/strong>que ella sea puente y camino para llevarnos a \u00c9l en todo momento, no se convierta en meta.<\/p>\n\n\n\n<p>Me permito terminar con unos versos del poeta espa\u00f1ol Antonio Machado:<\/p>\n\n\n\n<p><em>\u201cHoy es siempre todav\u00eda. Toda la vida es ahora.\u00a0Y ahora, ahora es el momento de cumplir las promesas que nos hicimos.\u00a0 Porque ayer no lo hicimos.\u00a0Porque ma\u00f1ana es tarde. Ahora\u201d.<\/em><\/p>\n\n\n\n<p><em><strong>Mar\u00eda Luisa Berzosa FI<\/strong>. <\/em><strong>Roma<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00ednodo de la Sinodalidad,\u00a0con tres acentos muy significativos:\u00a0 Participaci\u00f3n, Comuni\u00f3n,\u00a0 Misi\u00f3n, estamos participando en un proceso que nos afecta como iglesia y para el cual hemos recibido una invitaci\u00f3n universal. Todas las personas bautizadas que nos sentimos miembros activos de la iglesia como aquellas que se sienten alejadas o incluso quienes no tienen una fe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32045,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[532,412],"tags":[711],"class_list":["post-37653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-church","category-news","tag-sinodo-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El S\u00ednodo contin\u00faa - Hijas de Jes\u00fas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El S\u00ednodo contin\u00faa - Hijas de Jes\u00fas\" \/>\n<meta property=\"og:description\" content=\"S\u00ednodo de la Sinodalidad,\u00a0con tres acentos muy significativos:\u00a0 Participaci\u00f3n, Comuni\u00f3n,\u00a0 Misi\u00f3n, estamos participando en un proceso que nos afecta como iglesia y para el cual hemos recibido una invitaci\u00f3n universal. Todas las personas bautizadas que nos sentimos miembros activos de la iglesia como aquellas que se sienten alejadas o incluso quienes no tienen una fe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/\" \/>\n<meta property=\"og:site_name\" content=\"Hijas de Jes\u00fas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T19:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-14T19:21:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Beatriz Concejo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:site\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Concejo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/\"},\"author\":{\"name\":\"Beatriz Concejo\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#\\\/schema\\\/person\\\/a89333d7c811935bc234f49793356474\"},\"headline\":\"El S\u00ednodo contin\u00faa\",\"datePublished\":\"2023-12-14T19:21:00+00:00\",\"dateModified\":\"2023-12-14T19:21:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/\"},\"wordCount\":631,\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"keywords\":[\"S\u00ednodo\"],\"articleSection\":[\"Church\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/\",\"name\":\"El S\u00ednodo contin\u00faa - Hijas de Jes\u00fas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"datePublished\":\"2023-12-14T19:21:00+00:00\",\"dateModified\":\"2023-12-14T19:21:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"width\":1748,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/el-sinodo-continua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El S\u00ednodo contin\u00faa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/\",\"name\":\"Hijas de Jes\u00fas\",\"description\":\"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida\",\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#organization\",\"name\":\"Hijas de Jes\u00fas\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"width\":700,\"height\":360,\"caption\":\"Hijas de Jes\u00fas\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hijasdejesusenelmundo\\\/\",\"https:\\\/\\\/x.com\\\/hijasdjesus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/#\\\/schema\\\/person\\\/a89333d7c811935bc234f49793356474\",\"name\":\"Beatriz Concejo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g\",\"caption\":\"Beatriz Concejo\"},\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/en\\\/author\\\/bea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El S\u00ednodo contin\u00faa - Hijas de Jes\u00fas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/","og_locale":"en_US","og_type":"article","og_title":"El S\u00ednodo contin\u00faa - Hijas de Jes\u00fas","og_description":"S\u00ednodo de la Sinodalidad,\u00a0con tres acentos muy significativos:\u00a0 Participaci\u00f3n, Comuni\u00f3n,\u00a0 Misi\u00f3n, estamos participando en un proceso que nos afecta como iglesia y para el cual hemos recibido una invitaci\u00f3n universal. Todas las personas bautizadas que nos sentimos miembros activos de la iglesia como aquellas que se sienten alejadas o incluso quienes no tienen una fe [&hellip;]","og_url":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/","og_site_name":"Hijas de Jes\u00fas","article_publisher":"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","article_published_time":"2023-12-14T19:21:00+00:00","article_modified_time":"2023-12-14T19:21:16+00:00","og_image":[{"width":1748,"height":1240,"url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","type":"image\/png"}],"author":"Beatriz Concejo","twitter_card":"summary_large_image","twitter_creator":"@hijasdjesus","twitter_site":"@hijasdjesus","twitter_misc":{"Written by":"Beatriz Concejo","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/#article","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/"},"author":{"name":"Beatriz Concejo","@id":"https:\/\/hijasdejesus.org\/en\/#\/schema\/person\/a89333d7c811935bc234f49793356474"},"headline":"El S\u00ednodo contin\u00faa","datePublished":"2023-12-14T19:21:00+00:00","dateModified":"2023-12-14T19:21:16+00:00","mainEntityOfPage":{"@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/"},"wordCount":631,"publisher":{"@id":"https:\/\/hijasdejesus.org\/en\/#organization"},"image":{"@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","keywords":["S\u00ednodo"],"articleSection":["Church","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/","url":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/","name":"El S\u00ednodo contin\u00faa - Hijas de Jes\u00fas","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/#primaryimage"},"image":{"@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","datePublished":"2023-12-14T19:21:00+00:00","dateModified":"2023-12-14T19:21:16+00:00","breadcrumb":{"@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/#primaryimage","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","width":1748,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/hijasdejesus.org\/en\/el-sinodo-continua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hijasdejesus.org\/en\/"},{"@type":"ListItem","position":2,"name":"El S\u00ednodo contin\u00faa"}]},{"@type":"WebSite","@id":"https:\/\/hijasdejesus.org\/en\/#website","url":"https:\/\/hijasdejesus.org\/en\/","name":"Hijas de Jes\u00fas","description":"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida","publisher":{"@id":"https:\/\/hijasdejesus.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hijasdejesus.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hijasdejesus.org\/en\/#organization","name":"Hijas de Jes\u00fas","url":"https:\/\/hijasdejesus.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hijasdejesus.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","width":700,"height":360,"caption":"Hijas de Jes\u00fas"},"image":{"@id":"https:\/\/hijasdejesus.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","https:\/\/x.com\/hijasdjesus"]},{"@type":"Person","@id":"https:\/\/hijasdejesus.org\/en\/#\/schema\/person\/a89333d7c811935bc234f49793356474","name":"Beatriz Concejo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g","caption":"Beatriz Concejo"},"url":"https:\/\/hijasdejesus.org\/en\/author\/bea\/"}]}},"_links":{"self":[{"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/posts\/37653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/comments?post=37653"}],"version-history":[{"count":1,"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/posts\/37653\/revisions"}],"predecessor-version":[{"id":37656,"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/posts\/37653\/revisions\/37656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/media\/32045"}],"wp:attachment":[{"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/media?parent=37653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/categories?post=37653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hijasdejesus.org\/en\/wp-json\/wp\/v2\/tags?post=37653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}