{"id":27928,"date":"2016-10-10T18:58:45","date_gmt":"2016-10-10T16:58:45","guid":{"rendered":"https:\/\/nueva.hijasdejesus.org\/cg36-comeca-a-etapa-de-murmuratio\/"},"modified":"2016-10-11T17:29:00","modified_gmt":"2016-10-11T15:29:00","slug":"cg36-comeca-a-etapa-de-murmuratio","status":"publish","type":"post","link":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/","title":{"rendered":"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d"},"content":{"rendered":"<p>Talvez j\u00e1 tenham lido um dos artigos que descrevem as etapas da Congrega\u00e7\u00e3o Geral: um elemento espec\u00edfico do \u201cmodo de proceder\u201d dos jesu\u00edtas para a elei\u00e7\u00e3o de seu superior geral \u00e9 aquilo que se costuma chamar murmuratio. <br \/>Santo In\u00e1cio, nas Constitui\u00e7\u00f5es, insistiu fortemente para que a elei\u00e7\u00e3o do Geral se fizesse em clima de ora\u00e7\u00e3o e discernimento, um clima que deixe o primeiro lugar ao Esp\u00edrito Santo. Neste contexto n\u00e3o h\u00e1 lugar para partidos, campanhas, nem candidatos. De fato, qualquer jesu\u00edta do mundo pode ser eleito Geral- embora, habitualmente, costuma ser eleito um homem de experi\u00eancia que tenha sido eleito por sua prov\u00edncia jesu\u00edtica e que, portanto, \u00e9 membro da Congrega\u00e7\u00e3o-.<br \/>\u00c9 verdade que Santo In\u00e1cio privilegiou os meios espirituais para a elei\u00e7\u00e3o, mas n\u00e3o por isso esqueceu a import\u00e2ncia da intelig\u00eancia humana. Os eleitores devem se informar sobre as pessoas que estimem adequadas para assumir o governo universal da Companhia de Jesus. In\u00e1cio prop\u00f4s um m\u00e9todo \u00fanico, um per\u00edodo de alguns dias, durante os quais os eleitores conversam entre eles acerca das pessoas que consideram com possibilidade para chegar a ser superior geral. N\u00e3o se pode falar mais do que com uma pessoa de cada vez; nesta etapa n\u00e3o podem formar grupos de discuss\u00e3o. Nestes momentos de troca de informa\u00e7\u00e3o, cada um, coforme seu ritmo, frequenta a capela para rezar o que vai percebendo em suas conversas.<br \/>A murmuratio \u00e9 vivida de forma confidencial dentro da Curia, e durante este per\u00edodo n\u00e3o se pode perguntar aos eleitores sobre o que est\u00e3o vivendo ou intercambiando e que, guiados pelo Esp\u00edrito, se concluir\u00e1 na vota\u00e7\u00e3o em tal ou qual jesu\u00edta.\u00a0 Contudo, nos atrevemos a pedir ao Pe. Charles Chilinda, da prov\u00edncia jesu\u00edtica de Zambia-Malawi, que nos fale daquilo que recorda da murmuratio de 2008. Pe. Chilinda \u2013atualmente membro da equipe de v\u00eddeo da CG 36- foi delegado de sua Prov\u00edncia na \u00faltima Congrega\u00e7\u00e3o que elegeu o Pe. Adolfo Nicol\u00e1s. E ele nos contou:<br \/>\u201cEntre os jesu\u00edtas presentes, eu n\u00e3o conhecia mais que alguns membros procedentes da \u00c1frica e dos Estados Unidos. Comecei a me encontrar com uns e outros delegados e logo senti grande abertura e disponibilidade. Ouvi falar de jesu\u00edtas que n\u00e3o conhecia, mas que em pouco tempo pude ter uma imagem bastante clara desses homens. Como profissional do mundo audiovisual diria que parti de uma imagem desfocada que pouco a pouco se tornou n\u00edtida. Conversei com uns vinte companheiros e passei muito tempo no sil\u00eancio da ora\u00e7\u00e3o. Em nenhum momento senti que me pressionaram para tal ou qual candidato. Havia um forte clima de liberdade\u201d.\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Talvez j\u00e1 tenham lido um dos artigos que descrevem as etapas da Congrega\u00e7\u00e3o Geral: um elemento espec\u00edfico do \u201cmodo de proceder\u201d dos jesu\u00edtas para a elei\u00e7\u00e3o de seu superior geral \u00e9 aquilo que se costuma chamar murmuratio. Santo In\u00e1cio, nas Constitui\u00e7\u00f5es, insistiu fortemente para que a elei\u00e7\u00e3o do Geral se fizesse em clima de ora\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":7834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[469],"tags":[],"class_list":["post-27928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d - Hijas de Jes\u00fas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d - Hijas de Jes\u00fas\" \/>\n<meta property=\"og:description\" content=\"Talvez j\u00e1 tenham lido um dos artigos que descrevem as etapas da Congrega\u00e7\u00e3o Geral: um elemento espec\u00edfico do \u201cmodo de proceder\u201d dos jesu\u00edtas para a elei\u00e7\u00e3o de seu superior geral \u00e9 aquilo que se costuma chamar murmuratio. Santo In\u00e1cio, nas Constitui\u00e7\u00f5es, insistiu fortemente para que a elei\u00e7\u00e3o do Geral se fizesse em clima de ora\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/\" \/>\n<meta property=\"og:site_name\" content=\"Hijas de Jes\u00fas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-10T16:58:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-11T15:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2016\/10\/murmuratio_2-750x420.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:site\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/\"},\"author\":{\"name\":\"Webmaster\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/ce4455965da733f2791f23b6ec14e9b6\"},\"headline\":\"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d\",\"datePublished\":\"2016-10-10T16:58:45+00:00\",\"dateModified\":\"2016-10-11T15:29:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/\"},\"wordCount\":475,\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/murmuratio_2-750x420.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/\",\"name\":\"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d - Hijas de Jes\u00fas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/murmuratio_2-750x420.jpg\",\"datePublished\":\"2016-10-10T16:58:45+00:00\",\"dateModified\":\"2016-10-11T15:29:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/murmuratio_2-750x420.jpg\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/murmuratio_2-750x420.jpg\",\"width\":750,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/cg36-comeca-a-etapa-de-murmuratio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"name\":\"Hijas de Jes\u00fas\",\"description\":\"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida\",\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\",\"name\":\"Hijas de Jes\u00fas\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"width\":700,\"height\":360,\"caption\":\"Hijas de Jes\u00fas\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hijasdejesusenelmundo\\\/\",\"https:\\\/\\\/x.com\\\/hijasdjesus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/ce4455965da733f2791f23b6ec14e9b6\",\"name\":\"Webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g\",\"caption\":\"Webmaster\"},\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/author\\\/webmaster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d - Hijas de Jes\u00fas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/","og_locale":"pt_BR","og_type":"article","og_title":"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d - Hijas de Jes\u00fas","og_description":"Talvez j\u00e1 tenham lido um dos artigos que descrevem as etapas da Congrega\u00e7\u00e3o Geral: um elemento espec\u00edfico do \u201cmodo de proceder\u201d dos jesu\u00edtas para a elei\u00e7\u00e3o de seu superior geral \u00e9 aquilo que se costuma chamar murmuratio. Santo In\u00e1cio, nas Constitui\u00e7\u00f5es, insistiu fortemente para que a elei\u00e7\u00e3o do Geral se fizesse em clima de ora\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/","og_site_name":"Hijas de Jes\u00fas","article_publisher":"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","article_published_time":"2016-10-10T16:58:45+00:00","article_modified_time":"2016-10-11T15:29:00+00:00","og_image":[{"width":750,"height":420,"url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2016\/10\/murmuratio_2-750x420.jpg","type":"image\/jpeg"}],"author":"Webmaster","twitter_card":"summary_large_image","twitter_creator":"@hijasdjesus","twitter_site":"@hijasdjesus","twitter_misc":{"Escrito por":"Webmaster","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/#article","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/"},"author":{"name":"Webmaster","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/ce4455965da733f2791f23b6ec14e9b6"},"headline":"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d","datePublished":"2016-10-10T16:58:45+00:00","dateModified":"2016-10-11T15:29:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/"},"wordCount":475,"publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2016\/10\/murmuratio_2-750x420.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/","url":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/","name":"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d - Hijas de Jes\u00fas","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/#primaryimage"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2016\/10\/murmuratio_2-750x420.jpg","datePublished":"2016-10-10T16:58:45+00:00","dateModified":"2016-10-11T15:29:00+00:00","breadcrumb":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/#primaryimage","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2016\/10\/murmuratio_2-750x420.jpg","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2016\/10\/murmuratio_2-750x420.jpg","width":750,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/hijasdejesus.org\/pt-br\/cg36-comeca-a-etapa-de-murmuratio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hijasdejesus.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"CG36: Come\u00e7a a etapa de \u201cmurmuratio\u201d"}]},{"@type":"WebSite","@id":"https:\/\/hijasdejesus.org\/pt-br\/#website","url":"https:\/\/hijasdejesus.org\/pt-br\/","name":"Hijas de Jes\u00fas","description":"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida","publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hijasdejesus.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization","name":"Hijas de Jes\u00fas","url":"https:\/\/hijasdejesus.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","width":700,"height":360,"caption":"Hijas de Jes\u00fas"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","https:\/\/x.com\/hijasdjesus"]},{"@type":"Person","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/ce4455965da733f2791f23b6ec14e9b6","name":"Webmaster","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g","caption":"Webmaster"},"url":"https:\/\/hijasdejesus.org\/pt-br\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/27928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/comments?post=27928"}],"version-history":[{"count":0,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/27928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media\/7834"}],"wp:attachment":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media?parent=27928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/categories?post=27928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/tags?post=27928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}