{"id":29153,"date":"2020-03-22T19:14:35","date_gmt":"2020-03-22T18:14:35","guid":{"rendered":"https:\/\/nueva.hijasdejesus.org\/viagem-do-coracao-ii\/"},"modified":"2020-03-22T19:31:40","modified_gmt":"2020-03-22T18:31:40","slug":"viagem-do-coracao-ii","status":"publish","type":"post","link":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/","title":{"rendered":"Viagem do cora\u00e7\u00e3o (II)"},"content":{"rendered":"<p style=\"text-align: center;\">\n<p>\u00a0<span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">Desde o domingo passado, dia 15, quando escrevi minha primeira etapa da viagem, n\u00e3o imaginava que hoje tamb\u00e9m domingo fosse comemorar uma semana t\u00e3o densa quanto a que tivemos que viver.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">E antes de terminar, chegou a primavera, o dia da poesia, o dia de lembrar que a vida prevalece e atravessa o solo duro e pedregoso, um momento para alongar o olhar e acreditar que a semente precisa da escurid\u00e3o do sulco para nos dar flores e folhas. de cor e que chegar\u00e1 a hora de celebr\u00e1-lo como merece.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">Ficar em casa foi assimilando pouco a pouco todos os dias, a rotina era imponente, porque a estrada \u00e9 longa. A casa externa \u00e9 organizada, os tempos tamb\u00e9m, mas o cora\u00e7\u00e3o come\u00e7a a sentir tristeza, alternando com esperan\u00e7a, alegria com dor, pessoas conhecidas e desconhecidas que s\u00e3o infectadas e morrem, outras curam e engrossam a dif\u00edcil lista de descargas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">Talvez a sensa\u00e7\u00e3o mais forte desta semana tenha sido o crescimento incontrol\u00e1vel e a um ritmo verdadeiramente r\u00e1pido de cont\u00e1gio em tantas partes do planeta. Realmente, por um lado, nos sentimos muito insignificantes e, ao mesmo tempo, a pr\u00f3pria vida atinge dimens\u00f5es c\u00f3smicas, criatura do mundo, parte daquele planeta &#8211; aquela casa comum &#8211; e experimenta, como nunca antes, que nada do que acontece no mundo \u00e9 para mim alien\u00edgena.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">\u00c9 mais do que o mundo entrou em nossas casas e j\u00e1 somos insepar\u00e1veis. Essa consci\u00eancia c\u00f3smica da criatura, mesmo que pare\u00e7a um paradoxo, \u00e9 a imagem que melhor define o que eu vivo. Mas recebo not\u00edcias de pessoas saindo, conhecidas e n\u00e3o, com a imensa dor para aqueles que permanecem, de n\u00e3o poder dizer adeus; \u00c9 um duelo duplo dif\u00edcil de manter.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">Meus dias e momentos se alternam: paz, inquieta\u00e7\u00e3o, confian\u00e7a, incerteza, esperan\u00e7a, medo &#8230; A aus\u00eancia e distanciamento de fam\u00edlias, amigos, colegas de trabalho, irm\u00e3s da comunidade, a n\u00e3o sa\u00edda para a rua, o pequeno espa\u00e7o para onde se mover. ou\u00e7a o sil\u00eancio, \u00e0s vezes agradecido, mas outras vezes adquire uma densidade que pesa.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">E estamos incorporando rotinas di\u00e1rias &#8211; que s\u00e3o aconselhadas a permanecer o tempo que for necess\u00e1rio &#8211; para que possamos viver esse tempo com plena consci\u00eancia e n\u00e3o deix\u00e1-lo nos absorver sem assumir o comando. Dif\u00edcil para aqueles que precisam combinar a aten\u00e7\u00e3o de sua pr\u00f3pria fam\u00edlia com o compromisso de trabalho que eles tamb\u00e9m n\u00e3o podem abandonar.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">E estamos proporcionando al\u00edvio de forma criativa e, acima de tudo, solid\u00e1ria, deixando-nos pensar sobre como o outro \u00e9 e o outro: enviamos mensagens, ajudamos na reflex\u00e3o, rezamos, vivemos tudo isso com significado, mesmo sem quase entender. nada; Tamb\u00e9m sinto que uma rotina necess\u00e1ria \u00e9 distribuir as informa\u00e7\u00f5es avassaladoras que recebemos; todos com uma imensa vontade de ajudar, mas tamb\u00e9m podemos sufocar; saber escolher o que mais nos ajuda e tamb\u00e9m poder coloc\u00e1-lo no crono di\u00e1rio ap\u00f3s os kair\u00f3s.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial;\"><br \/> Estamos tendo reuni\u00f5es com poucas ou muitas pessoas, com nossos colegas de trabalho e vemos, olhamos e sorrimos atrav\u00e9s da tela que, no meio de tudo, nos aproxima e confirma que continuamos fortes e misteriosamente unidos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">Recebemos not\u00edcias da ampla fam\u00edlia religiosa espalhada pelo mundo que nos confortam e nos ajudam a permanecer o mais pac\u00edfico poss\u00edvel. Incorporamos a Eucaristia, momentos de ora\u00e7\u00e3o, encontros dentro de casa, sempre com uma consci\u00eancia universal.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">E tamb\u00e9m incorporamos uma rotina empolgante: todas as noites, nos juntamos ao pa\u00eds que se tornou uma varanda grata aos nossos funcion\u00e1rios &#8211; sa\u00fade e muitos outros &#8211; que ap\u00f3iam nossa sociedade, e oferecemos a cada bairro nossos calorosos aplausos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">E continuo minha jornada sem sair de casa, divulgando esse momento e compartilhando minhas experi\u00eancias, caso ajudem outras pessoas. Eu continuo aprendendo, tirando li\u00e7\u00f5es deste est\u00e1gio nunca imaginadas, mas reais; com f\u00e9 e esperan\u00e7a no Deus da hist\u00f3ria que caminha ao nosso lado, mas que em momentos de fraqueza nos leva a nos perguntar: \u201conde voc\u00ea est\u00e1? Voc\u00ea nos abandonou?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">E ouvimos em nossos cora\u00e7\u00f5es uma palavra que conforta e encoraja: &#8220;N\u00e3o tema, eu estou com voc\u00ea&#8221;; \u201cOlhe ao seu redor, em todo o mundo h\u00e1 muitas doa\u00e7\u00f5es generosas e an\u00f4nimas, \u00e9 despertada uma solidariedade que atravessa fronteiras e traz o melhor de todo ser humano; h\u00e1 uma busca cont\u00ednua para nos ajudar &#8230; l\u00e1 estou eu, na vida e na morte, apoiando e confortando, abra bem seus olhos, voc\u00ea ver\u00e1 como descobrir\u00e1 como e onde n\u00e3o imagina \u201d.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span lang=\"PT\" style=\"font-size: 12.0pt; line-height: 115%; font-family: 'Candara','sans-serif'; mso-bidi-font-family: Arial; mso-ansi-language: PT;\">E continuamos em casa, renovando nosso compromisso de cuidar de n\u00f3s mesmos; para nos manter em uni\u00e3o comum. Mais uma semana que esperamos sinceramente trar\u00e1 al\u00edvio ao nosso mundo ferido. Enquanto isso, n\u00e3o paramos de sorrir, que nosso rosto n\u00e3o endurece porque precisamos um do outro e esperan\u00e7osos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: right;\"><span style=\"font-size: 12pt;\"><em><strong><span style=\"line-height: 115%; font-family: Candara, sans-serif;\">Mar\u00eda Luisa Berzosa fi<\/span><\/strong><\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: right;\"><span style=\"font-size: 12pt;\"><em><strong><span style=\"line-height: 115%; font-family: Candara, sans-serif;\">Entrev\u00edas &#8211;<span style=\"mso-spacerun: yes;\">\u00a0 <\/span>Madrid<\/span><\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Desde o domingo passado, dia 15, quando escrevi minha primeira etapa da viagem, n\u00e3o imaginava que hoje tamb\u00e9m domingo fosse comemorar uma semana t\u00e3o densa quanto a que tivemos que viver. E antes de terminar, chegou a primavera, o dia da poesia, o dia de lembrar que a vida prevalece e atravessa o solo duro [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":10114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[521,529,469],"tags":[],"class_list":["post-29153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espanha-italia","category-hijas-de-jesus-pt-br","category-noticias-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viagem do cora\u00e7\u00e3o (II) - Hijas de Jes\u00fas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viagem do cora\u00e7\u00e3o (II) - Hijas de Jes\u00fas\" \/>\n<meta property=\"og:description\" content=\"\u00a0Desde o domingo passado, dia 15, quando escrevi minha primeira etapa da viagem, n\u00e3o imaginava que hoje tamb\u00e9m domingo fosse comemorar uma semana t\u00e3o densa quanto a que tivemos que viver. E antes de terminar, chegou a primavera, o dia da poesia, o dia de lembrar que a vida prevalece e atravessa o solo duro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Hijas de Jes\u00fas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-22T18:14:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-22T18:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2020\/03\/map-of-the-world-2401458_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1151\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:site\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/\"},\"author\":{\"name\":\"Webmaster\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/ce4455965da733f2791f23b6ec14e9b6\"},\"headline\":\"Viagem do cora\u00e7\u00e3o (II)\",\"datePublished\":\"2020-03-22T18:14:35+00:00\",\"dateModified\":\"2020-03-22T18:31:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/\"},\"wordCount\":864,\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/map-of-the-world-2401458_1920.jpg\",\"articleSection\":[\"Espanha-It\u00e1lia\",\"Hijas de Jes\u00fas\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/\",\"name\":\"Viagem do cora\u00e7\u00e3o (II) - Hijas de Jes\u00fas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/map-of-the-world-2401458_1920.jpg\",\"datePublished\":\"2020-03-22T18:14:35+00:00\",\"dateModified\":\"2020-03-22T18:31:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/map-of-the-world-2401458_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/map-of-the-world-2401458_1920.jpg\",\"width\":1920,\"height\":1151},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/viagem-do-coracao-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viagem do cora\u00e7\u00e3o (II)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"name\":\"Hijas de Jes\u00fas\",\"description\":\"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida\",\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\",\"name\":\"Hijas de Jes\u00fas\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"width\":700,\"height\":360,\"caption\":\"Hijas de Jes\u00fas\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hijasdejesusenelmundo\\\/\",\"https:\\\/\\\/x.com\\\/hijasdjesus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/ce4455965da733f2791f23b6ec14e9b6\",\"name\":\"Webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g\",\"caption\":\"Webmaster\"},\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/author\\\/webmaster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viagem do cora\u00e7\u00e3o (II) - Hijas de Jes\u00fas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/","og_locale":"pt_BR","og_type":"article","og_title":"Viagem do cora\u00e7\u00e3o (II) - Hijas de Jes\u00fas","og_description":"\u00a0Desde o domingo passado, dia 15, quando escrevi minha primeira etapa da viagem, n\u00e3o imaginava que hoje tamb\u00e9m domingo fosse comemorar uma semana t\u00e3o densa quanto a que tivemos que viver. E antes de terminar, chegou a primavera, o dia da poesia, o dia de lembrar que a vida prevalece e atravessa o solo duro [&hellip;]","og_url":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/","og_site_name":"Hijas de Jes\u00fas","article_publisher":"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","article_published_time":"2020-03-22T18:14:35+00:00","article_modified_time":"2020-03-22T18:31:40+00:00","og_image":[{"width":1920,"height":1151,"url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2020\/03\/map-of-the-world-2401458_1920.jpg","type":"image\/jpeg"}],"author":"Webmaster","twitter_card":"summary_large_image","twitter_creator":"@hijasdjesus","twitter_site":"@hijasdjesus","twitter_misc":{"Escrito por":"Webmaster","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/#article","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/"},"author":{"name":"Webmaster","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/ce4455965da733f2791f23b6ec14e9b6"},"headline":"Viagem do cora\u00e7\u00e3o (II)","datePublished":"2020-03-22T18:14:35+00:00","dateModified":"2020-03-22T18:31:40+00:00","mainEntityOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/"},"wordCount":864,"publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2020\/03\/map-of-the-world-2401458_1920.jpg","articleSection":["Espanha-It\u00e1lia","Hijas de Jes\u00fas","Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/","url":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/","name":"Viagem do cora\u00e7\u00e3o (II) - Hijas de Jes\u00fas","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/#primaryimage"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2020\/03\/map-of-the-world-2401458_1920.jpg","datePublished":"2020-03-22T18:14:35+00:00","dateModified":"2020-03-22T18:31:40+00:00","breadcrumb":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/#primaryimage","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2020\/03\/map-of-the-world-2401458_1920.jpg","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2020\/03\/map-of-the-world-2401458_1920.jpg","width":1920,"height":1151},{"@type":"BreadcrumbList","@id":"https:\/\/hijasdejesus.org\/pt-br\/viagem-do-coracao-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hijasdejesus.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Viagem do cora\u00e7\u00e3o (II)"}]},{"@type":"WebSite","@id":"https:\/\/hijasdejesus.org\/pt-br\/#website","url":"https:\/\/hijasdejesus.org\/pt-br\/","name":"Hijas de Jes\u00fas","description":"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida","publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hijasdejesus.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization","name":"Hijas de Jes\u00fas","url":"https:\/\/hijasdejesus.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","width":700,"height":360,"caption":"Hijas de Jes\u00fas"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","https:\/\/x.com\/hijasdjesus"]},{"@type":"Person","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/ce4455965da733f2791f23b6ec14e9b6","name":"Webmaster","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfd0acaac86c3981d541d2e99a0ffb7b6d33a5ac8989a62f5518b9e0f7ee128a?s=96&d=mm&r=g","caption":"Webmaster"},"url":"https:\/\/hijasdejesus.org\/pt-br\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/29153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/comments?post=29153"}],"version-history":[{"count":0,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/29153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media\/10114"}],"wp:attachment":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media?parent=29153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/categories?post=29153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/tags?post=29153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}