{"id":33697,"date":"2023-04-17T21:16:00","date_gmt":"2023-04-17T19:16:00","guid":{"rendered":"https:\/\/hijasdejesus.org\/palco-continental-sinodo-de-marco-de-2023-2\/"},"modified":"2023-05-12T10:34:59","modified_gmt":"2023-05-12T08:34:59","slug":"palco-continental-sinodo-de-marco-de-2023-2","status":"publish","type":"post","link":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/","title":{"rendered":"Fase continental &#8211; S\u00ednodo de Abril de 2023"},"content":{"rendered":"\n<p>Enquanto isso, as sess\u00f5es correspondentes \u00e0<strong>Etapa Continental do S\u00ednodo<\/strong> continuam, no per\u00edodo que antecede a Assembleia, no pr\u00f3ximo m\u00eas de Outubro, h\u00e1 tamb\u00e9m movimento em prepara\u00e7\u00e3o para a Assembleia.<\/p>\n\n<p>Existe uma <strong>Constitui\u00e7\u00e3o Apost\u00f3lica<\/strong> <em>Episcopal Communio<\/em> que <strong>recomenda no Artigo 10, I-2, a cria\u00e7\u00e3o de uma comiss\u00e3o preparat\u00f3ria para uma tal Assembleia.<\/strong><\/p>\n\n<p>Em virtude do mesmo, o Secret\u00e1rio-Geral do S\u00ednodo, <em><strong>Cart\u00e3o. Mario Grech,<\/strong><\/em> constituiu a <strong>Comiss\u00e3o Preparat\u00f3ria da XVI Assembleia Geral Ordin\u00e1ria do S\u00ednodo dos Bispos,<\/strong>que ser\u00e1 presidida por ele pr\u00f3prio, com as seguintes pessoas<\/p>\n\n<p>&#8211; <strong><em>P. Giacomo Costa, SJ <\/em><\/strong>(coordenador)<\/p>\n\n<p>&#8211;  <strong><em>Mons. Timothy John Costelloe, SD<\/em><\/strong><\/p>\n\n<p>&#8211;  <strong><em>Mons. Daniel E. Flores<\/em><\/strong><\/p>\n\n<p>&#8211;<strong><em> Sr. Shizue Hirota, MMB<\/em><\/strong><\/p>\n\n<p>&#8211;  <strong><em>Mons. Lucius A. Muandula<\/em><\/strong><\/p>\n\n<p>&#8211; <strong><em>Prof. Dario Vitali<\/em><\/strong><\/p>\n\n<p>&#8211;  <strong><em>Mons. Tomasz Trafny<\/em><\/strong> (secret\u00e1rio)<\/p>\n\n<p>O Relator Geral do S\u00ednodo tamb\u00e9m participar\u00e1 nos trabalhos da Comiss\u00e3o,<strong><em> Cart\u00e3o. Jean-Claude Hollerich, SJ.<\/em><\/strong><\/p>\n\n<p>Para al\u00e9m desta not\u00edcia sobre a prepara\u00e7\u00e3o da Assembleia Sinodal de uma forma pr\u00e1tica, <strong>fazemos eco de uma dimens\u00e3o muito sinodal <\/strong>que \u00e9 recomendada para participa\u00e7\u00e3o a todos os n\u00edveis, que \u00e9 a <strong>conversa espiritual<\/strong>.<\/p>\n\n<p>Este modo de conversa centra-se na <strong>qualidade da audi\u00e7\u00e3o, bem como na qualidade das palavras faladas<\/strong>. Isto significa prestar aten\u00e7\u00e3o aos movimentos espirituais em si pr\u00f3prio e na outra pessoa durante a conversa, o que exige estar atento a mais do que apenas \u00e0s palavras expressas. Esta qualidade de cuidado \u00e9 um <strong>ato de respeito, acolhimento e hospitalidade para com os outros e como filho.<\/strong>.<\/p>\n\n<p>\u00c9 uma abordagem que leva a s\u00e9rio o que se passa no cora\u00e7\u00e3o de quem est\u00e1 em conversa\u00e7\u00e3o. H\u00e1 <strong>duas atitudes<\/strong> necess\u00e1rias que s\u00e3o fundamentais neste processo: <strong>ouvir ativamente e falar a partir do cora\u00e7\u00e3o<\/strong>. O objetivo da conversa espiritual \u00e9 <strong>criar uma atmosfera de confian\u00e7a e de acolhimento<\/strong>, para que as pessoas possam expressar mais livremente. Isto ajuda-os a levar a s\u00e9rio o que se passa no seu interior quando ouvem os outros e falam.<\/p>\n\n<p>Em \u00faltima an\u00e1lise, esta aten\u00e7\u00e3o interior torna-nos <strong>mais conscientes da presen\u00e7a e participa\u00e7\u00e3o do Esp\u00edrito Santo no processo de partilha e discernimento.<\/strong>A conversa espiritual concentra-se na pessoa que estamos ouvindo, em n\u00f3s pr\u00f3prios e naquilo que experimentamos a um n\u00edvel espiritual. A quest\u00e3o fundamental \u00e9:<strong> O que est\u00e1 acontecendo com a outra pessoa e em mim, e como est\u00e1 o Senhor agindo sobre isso?<\/strong><\/p>\n\n<p><strong>Continuamos caminhando em sinodalidade com o cora\u00e7\u00e3o aberto <\/strong>\u00e0s mensagens que nos chegam do Senhor, atrav\u00e9s dos sinais dos tempos, a fim de discernir a melhor resposta aos seus planos.<\/p>\n\n<p><strong><em>Maria Luisa Berzosa FI,<\/em> Roma.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto isso, as sess\u00f5es correspondentes \u00e0Etapa Continental do S\u00ednodo continuam, no per\u00edodo que antecede a Assembleia, no pr\u00f3ximo m\u00eas de Outubro, h\u00e1 tamb\u00e9m movimento em prepara\u00e7\u00e3o para a Assembleia. Existe uma Constitui\u00e7\u00e3o Apost\u00f3lica Episcopal Communio que recomenda no Artigo 10, I-2, a cria\u00e7\u00e3o de uma comiss\u00e3o preparat\u00f3ria para uma tal Assembleia. Em virtude do mesmo, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[533,469],"tags":[712],"class_list":["post-33697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-igreja","category-noticias-pt-br","tag-sinodo-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fase continental - S\u00ednodo de Abril de 2023 - Hijas de Jes\u00fas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fase continental - S\u00ednodo de Abril de 2023 - Hijas de Jes\u00fas\" \/>\n<meta property=\"og:description\" content=\"Enquanto isso, as sess\u00f5es correspondentes \u00e0Etapa Continental do S\u00ednodo continuam, no per\u00edodo que antecede a Assembleia, no pr\u00f3ximo m\u00eas de Outubro, h\u00e1 tamb\u00e9m movimento em prepara\u00e7\u00e3o para a Assembleia. Existe uma Constitui\u00e7\u00e3o Apost\u00f3lica Episcopal Communio que recomenda no Artigo 10, I-2, a cria\u00e7\u00e3o de uma comiss\u00e3o preparat\u00f3ria para uma tal Assembleia. Em virtude do mesmo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Hijas de Jes\u00fas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T19:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-12T08:34:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Beatriz Concejo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:site\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Concejo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/\"},\"author\":{\"name\":\"Beatriz Concejo\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/a89333d7c811935bc234f49793356474\"},\"headline\":\"Fase continental &#8211; S\u00ednodo de Abril de 2023\",\"datePublished\":\"2023-04-17T19:16:00+00:00\",\"dateModified\":\"2023-05-12T08:34:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"keywords\":[\"S\u00ednodo\"],\"articleSection\":[\"Igreja\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/\",\"name\":\"Fase continental - S\u00ednodo de Abril de 2023 - Hijas de Jes\u00fas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"datePublished\":\"2023-04-17T19:16:00+00:00\",\"dateModified\":\"2023-05-12T08:34:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Portada-Sinodo.png\",\"width\":1748,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/palco-continental-sinodo-de-marco-de-2023-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fase continental &#8211; S\u00ednodo de Abril de 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"name\":\"Hijas de Jes\u00fas\",\"description\":\"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida\",\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\",\"name\":\"Hijas de Jes\u00fas\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"width\":700,\"height\":360,\"caption\":\"Hijas de Jes\u00fas\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hijasdejesusenelmundo\\\/\",\"https:\\\/\\\/x.com\\\/hijasdjesus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/a89333d7c811935bc234f49793356474\",\"name\":\"Beatriz Concejo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g\",\"caption\":\"Beatriz Concejo\"},\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/author\\\/bea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fase continental - S\u00ednodo de Abril de 2023 - Hijas de Jes\u00fas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Fase continental - S\u00ednodo de Abril de 2023 - Hijas de Jes\u00fas","og_description":"Enquanto isso, as sess\u00f5es correspondentes \u00e0Etapa Continental do S\u00ednodo continuam, no per\u00edodo que antecede a Assembleia, no pr\u00f3ximo m\u00eas de Outubro, h\u00e1 tamb\u00e9m movimento em prepara\u00e7\u00e3o para a Assembleia. Existe uma Constitui\u00e7\u00e3o Apost\u00f3lica Episcopal Communio que recomenda no Artigo 10, I-2, a cria\u00e7\u00e3o de uma comiss\u00e3o preparat\u00f3ria para uma tal Assembleia. Em virtude do mesmo, [&hellip;]","og_url":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/","og_site_name":"Hijas de Jes\u00fas","article_publisher":"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","article_published_time":"2023-04-17T19:16:00+00:00","article_modified_time":"2023-05-12T08:34:59+00:00","og_image":[{"width":1748,"height":1240,"url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","type":"image\/png"}],"author":"Beatriz Concejo","twitter_card":"summary_large_image","twitter_creator":"@hijasdjesus","twitter_site":"@hijasdjesus","twitter_misc":{"Escrito por":"Beatriz Concejo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#article","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/"},"author":{"name":"Beatriz Concejo","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/a89333d7c811935bc234f49793356474"},"headline":"Fase continental &#8211; S\u00ednodo de Abril de 2023","datePublished":"2023-04-17T19:16:00+00:00","dateModified":"2023-05-12T08:34:59+00:00","mainEntityOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","keywords":["S\u00ednodo"],"articleSection":["Igreja","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/","url":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/","name":"Fase continental - S\u00ednodo de Abril de 2023 - Hijas de Jes\u00fas","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#primaryimage"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","datePublished":"2023-04-17T19:16:00+00:00","dateModified":"2023-05-12T08:34:59+00:00","breadcrumb":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#primaryimage","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/02\/Portada-Sinodo.png","width":1748,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/hijasdejesus.org\/pt-br\/palco-continental-sinodo-de-marco-de-2023-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hijasdejesus.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Fase continental &#8211; S\u00ednodo de Abril de 2023"}]},{"@type":"WebSite","@id":"https:\/\/hijasdejesus.org\/pt-br\/#website","url":"https:\/\/hijasdejesus.org\/pt-br\/","name":"Hijas de Jes\u00fas","description":"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida","publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hijasdejesus.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization","name":"Hijas de Jes\u00fas","url":"https:\/\/hijasdejesus.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","width":700,"height":360,"caption":"Hijas de Jes\u00fas"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","https:\/\/x.com\/hijasdjesus"]},{"@type":"Person","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/a89333d7c811935bc234f49793356474","name":"Beatriz Concejo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3075c01a99ba1b38ab876c1780b5fe86903d79b830670c26b7f45a65200e807a?s=96&d=mm&r=g","caption":"Beatriz Concejo"},"url":"https:\/\/hijasdejesus.org\/pt-br\/author\/bea\/"}]}},"_links":{"self":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/33697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/comments?post=33697"}],"version-history":[{"count":6,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/33697\/revisions"}],"predecessor-version":[{"id":34120,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/33697\/revisions\/34120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media\/32046"}],"wp:attachment":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media?parent=33697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/categories?post=33697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/tags?post=33697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}