{"id":48072,"date":"2025-04-27T01:00:00","date_gmt":"2025-04-26T23:00:00","guid":{"rendered":"https:\/\/hijasdejesus.org\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/"},"modified":"2025-04-27T01:00:23","modified_gmt":"2025-04-26T23:00:23","slug":"seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day","status":"publish","type":"post","link":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/","title":{"rendered":"&#8220;Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa&#8221; &#8211; Anto\u00f1ita Day"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><em>27 de abril, Beata Maria Antonia Bandr\u00e9s El\u00f3segui, Filha de Jesus.<\/em><\/strong><\/p>\n\n<p>Hoje celebramos o dia de Anto\u00f1ita, como carinhosamente conhecemos a Beata Maria Antonia Bandr\u00e9s, Filha de Jesus (Tolosa, 6 de mar\u00e7o de 1898 &#8211; Salamanca, 27 de abril de 1919). <\/p>\n\n<p>A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e eventos. Somos convidados a dar uma olhada mais de perto no &#8220;entrela\u00e7amento desses fios&#8221; e em seu significado para nossas vidas. <\/p>\n\n<ul class=\"wp-block-list\">\n<li>\u00c9 o segundo domingo da P\u00e1scoa<\/li>\n\n\n\n<li>\u00c9 o Domingo da Divina Miseric\u00f3rdia<\/li>\n\n\n\n<li>Nosso amado Papa Francisco acaba de ser enterrado.<\/li>\n\n\n\n<li>27 de abril Ano do Jubileu Peregrinos da Esperan\u00e7a. Jubileu dos adolescentes. <\/li>\n\n\n\n<li>J\u00e1 se passou uma semana desde o in\u00edcio do CGXXIX. Com Ele, o caminho da esperan\u00e7a. <\/li>\n\n\n\n<li>E \u00e9 o dia da festa da Beata M\u00aa Antonia Bandr\u00e9s (Anto\u00f1ita), padroeira das Filhas de Jesus na forma\u00e7\u00e3o inicial e modelo de vida para a FASFI.<\/li>\n<\/ul>\n\n<p>Com essa &#8220;composi\u00e7\u00e3o de lugar&#8221;, vamos passar pelo cora\u00e7\u00e3o algumas pinceladas dessa dimens\u00e3o de compromisso com os pobres, da vida de Anto\u00f1ita, que nos ajudar\u00e3o a &#8220;refletir para tirar algum proveito&#8221; para nossa vida hoje.  <\/p>\n\n<p>Saber de onde veio o amor e o servi\u00e7o de Anto\u00f1ita aos pobres pode ajudar cada um de n\u00f3s a querer se conhecer melhor, a crescer como pessoas e a perceber que apostamos nossa vida no que fazemos com o que somos&#8230; porque nossas qualidades e limites, colocados a servi\u00e7o do bem e comprometidos com nosso processo de crescimento, podem dar muito amor e ajudar muitas pessoas.  <\/p>\n\n<p>A primeira caracter\u00edstica do temperamento de Anto\u00f1ita que os testemunhos coincidem em apontar, e mais frequentemente seus familiares, \u00e9 sua extrema sensibilidade, uma sensibilidade que, com toda a sua riqueza e dons, era tamb\u00e9m um verdadeiro inc\u00f4modo para aqueles que conviviam com ela. Sua pr\u00f3pria m\u00e3e, provavelmente em um desses momentos de particular cansa\u00e7o, exclamou: &#8220;Oh, minha filha, quanto voc\u00ea vai sofrer com esse car\u00e1ter, que menina cansativa!<\/p>\n\n<p>Sua m\u00e3e n\u00e3o estava errada ao pressentir que a filha sofreria na vida, mas estava errada ao atribuir a causa principal desse sofrimento ao seu modo de ser. Maria Antonia conseguiu se superar de tal forma que seu jeito se tornou agrad\u00e1vel a todos quando se aproximavam dela. <\/p>\n\n<p>O que a fazia sofrer era sua grande sensibilidade. Seu cora\u00e7\u00e3o, que &#8220;sentia muito as coisas&#8221;, apaixonado e sempre aberto para os outros e para Deus, dificilmente poderia permanecer impass\u00edvel. Mas, da mesma forma, essa mesma sensibilidade a dotava de uma riqueza que ela sabia aproveitar ao m\u00e1ximo.  <\/p>\n\n<p>  N\u00e3o h\u00e1 d\u00favida de que a sensibilidade \u00e9 um dom porque nos permite dialogar com a realidade, tanto a nossa pr\u00f3pria realidade interna quanto a que est\u00e1 al\u00e9m de n\u00f3s mesmos, porque nos permite sintonizar com tudo ao nosso redor e tomar consci\u00eancia disso; porque nos d\u00e1 intui\u00e7\u00e3o e empatia com as necessidades, os desejos e os sentimentos dos outros. Ela &#8220;sentia muito as coisas&#8221;, diziam a seu respeito, e assim, sentindo-as como se fossem suas, era r\u00e1pida para confortar, ajudar, aconselhar ou at\u00e9 mesmo quebrar barreiras sociais. <\/p>\n\n<p>Uma testemunha nos disse:<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>&#8220;Havia uma velha malvada na aldeia e ela costumava ir \u00e0 igreja \u00e0 noite. Todos fugiam dela, mas Anto\u00f1ita ia at\u00e9 ela e acendia seu livro com um f\u00f3sforo para ajud\u00e1-la a ler seu livro de ora\u00e7\u00f5es. Ela pegava o livro e o lia para ele. Quando encontrava os pobres ou os idosos na rua, sempre tinha uma palavra de conforto para eles.     <\/em><\/p>\n\n\n\n<p><em>&#8220;Havia um costume de que, ao ir para a escola, as meninas livres iam em uma cal\u00e7ada e as meninas pagas iam na outra (&#8230;) Anto\u00f1ita acompanhava as meninas pobres em sua cal\u00e7ada&#8221;.<\/em><\/p>\n<\/blockquote>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"D\u00eda de Anto\u00f1ita\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/TPZU4WSFN_U?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p>H\u00e1 muitos testemunhos que nos falam de sua disposi\u00e7\u00e3o para servir e trabalhar, qualquer trabalho, a qualquer momento e sem distin\u00e7\u00e3o de pessoas. Ela n\u00e3o buscava nenhum tipo de reconhecimento; seu desejo era servir, servir a todos e quanto mais, melhor, porque era o que seu amado Jesus havia feito e essa era uma das formas privilegiadas de se assemelhar a Ele. Por isso, sua disponibilidade era absoluta, em casa com os pais e com as empregadas, com os amigos, com os trabalhadores do sindicato, com qualquer pessoa que precisasse.  <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>&#8220;Ela era muito trabalhadora. Ela sempre gostou de ajudar as empregadas e como fazia isso bem&#8221; (&#8230;) ela estava sempre ajudando as meninas (&#8230;) quando pens\u00e1vamos que ela estava dormindo, ela se levantava e ia para a cozinha ajud\u00e1-las a limpar a lou\u00e7a, os sapatos e assim por diante&#8221;.<\/em><\/p>\n<\/blockquote>\n\n<p>Anto\u00f1ita foi apresentada ao mundo do trabalho por sua m\u00e3e. Entre os v\u00e1rios sindicatos que operavam no mundo do trabalho naquela \u00e9poca, havia o sindicato cat\u00f3lico, no qual ela realizava uma grande quantidade de trabalho social. Ela trabalhou com entusiasmo no treinamento de trabalhadoras: nas primeiras horas da noite, atendia cerca de vinte jovens trabalhadoras. Ela as ensinava a ler e escrever, a fazer bordados e outras tarefas dom\u00e9sticas, e tamb\u00e9m lhes ensinava can\u00e7\u00f5es religiosas e o folclore basco, quebrando assim o ritmo de outras tarefas mais mon\u00f3tonas. Mas isso n\u00e3o era tudo: por meio desse centro de estudos, ela passou a conhec\u00ea-las pessoalmente, tornou-se amiga delas, soube de seus problemas e se interessou por cada uma delas em particular.    <\/p>\n\n<p>Ela tamb\u00e9m dava aulas de catecismo para os trabalhadores que as desejavam: n\u00e3o desperdi\u00e7ava nenhuma oportunidade de aproximar as pessoas de Deus. E como ela fazia isso naturalmente! Ela deu o melhor de si para esse trabalho.  <\/p>\n\n<p><strong><em>O que esse aspecto da vida de Anto\u00f1ita reflete sobre voc\u00ea? O que voc\u00ea se sente convidado a fazer? <\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>27 de abril, Beata Maria Antonia Bandr\u00e9s El\u00f3segui, Filha de Jesus. Hoje celebramos o dia de Anto\u00f1ita, como carinhosamente conhecemos a Beata Maria Antonia Bandr\u00e9s, Filha de Jesus (Tolosa, 6 de mar\u00e7o de 1898 &#8211; Salamanca, 27 de abril de 1919). A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":48056,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[523,38,529,537,991,469],"tags":[859],"class_list":["post-48072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fasfi-pt-br","category-fi-pt-br","category-hijas-de-jesus-pt-br","category-juventude","category-liturgia-oracion-pt-br","category-noticias-pt-br","tag-antonita-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa&quot; - Anto\u00f1ita Day - Hijas de Jes\u00fas<\/title>\n<meta name=\"description\" content=\"A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e eventos. Somos convidados a dar uma olhada mais de perto no &quot;entrela\u00e7amento desses fios&quot; e em seu significado para nossas vidas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa&quot; - Anto\u00f1ita Day - Hijas de Jes\u00fas\" \/>\n<meta property=\"og:description\" content=\"A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e eventos. Somos convidados a dar uma olhada mais de perto no &quot;entrela\u00e7amento desses fios&quot; e em seu significado para nossas vidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Hijas de Jes\u00fas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-26T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-26T23:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2025\/04\/CartasSup.G.-Portada-18-1024x726.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n Internacional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:site\" content=\"@hijasdjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n Internacional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n Internacional\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/91b9e676dca8842a983b89793a34e5b8\"},\"headline\":\"&#8220;Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa&#8221; &#8211; Anto\u00f1ita Day\",\"datePublished\":\"2025-04-26T23:00:00+00:00\",\"dateModified\":\"2025-04-26T23:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/\"},\"wordCount\":999,\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CartasSup.G.-Portada-18.png\",\"keywords\":[\"Anto\u00f1ita\"],\"articleSection\":[\"FASFI\",\"fi\",\"Hijas de Jes\u00fas\",\"Juventude\",\"Liturgia &#8211; oraci\u00f3n\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/\",\"name\":\"\\\"Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa\\\" - Anto\u00f1ita Day - Hijas de Jes\u00fas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CartasSup.G.-Portada-18.png\",\"datePublished\":\"2025-04-26T23:00:00+00:00\",\"dateModified\":\"2025-04-26T23:00:23+00:00\",\"description\":\"A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e eventos. Somos convidados a dar uma olhada mais de perto no \\\"entrela\u00e7amento desses fios\\\" e em seu significado para nossas vidas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CartasSup.G.-Portada-18.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CartasSup.G.-Portada-18.png\",\"width\":2185,\"height\":1550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa&#8221; &#8211; Anto\u00f1ita Day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"name\":\"Hijas de Jes\u00fas\",\"description\":\"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida\",\"publisher\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#organization\",\"name\":\"Hijas de Jes\u00fas\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"contentUrl\":\"https:\\\/\\\/hijasdejesus.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Hijas-de-Jesus_hor-A7C957.png\",\"width\":700,\"height\":360,\"caption\":\"Hijas de Jes\u00fas\"},\"image\":{\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hijasdejesusenelmundo\\\/\",\"https:\\\/\\\/x.com\\\/hijasdjesus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/91b9e676dca8842a983b89793a34e5b8\",\"name\":\"Comunicaci\u00f3n Internacional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dcb9b61797c934872aa9209ebf48b92edfeb0819dcdcaa77cd84879d6def414d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dcb9b61797c934872aa9209ebf48b92edfeb0819dcdcaa77cd84879d6def414d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dcb9b61797c934872aa9209ebf48b92edfeb0819dcdcaa77cd84879d6def414d?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n Internacional\"},\"url\":\"https:\\\/\\\/hijasdejesus.org\\\/pt-br\\\/author\\\/comunicacion-internacional\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa\" - Anto\u00f1ita Day - Hijas de Jes\u00fas","description":"A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e eventos. Somos convidados a dar uma olhada mais de perto no \"entrela\u00e7amento desses fios\" e em seu significado para nossas vidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/","og_locale":"pt_BR","og_type":"article","og_title":"\"Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa\" - Anto\u00f1ita Day - Hijas de Jes\u00fas","og_description":"A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e eventos. Somos convidados a dar uma olhada mais de perto no \"entrela\u00e7amento desses fios\" e em seu significado para nossas vidas.","og_url":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/","og_site_name":"Hijas de Jes\u00fas","article_publisher":"https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","article_published_time":"2025-04-26T23:00:00+00:00","article_modified_time":"2025-04-26T23:00:23+00:00","og_image":[{"width":1024,"height":726,"url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2025\/04\/CartasSup.G.-Portada-18-1024x726.png","type":"image\/png"}],"author":"Comunicaci\u00f3n Internacional","twitter_card":"summary_large_image","twitter_creator":"@hijasdjesus","twitter_site":"@hijasdjesus","twitter_misc":{"Escrito por":"Comunicaci\u00f3n Internacional","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/#article","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/"},"author":{"name":"Comunicaci\u00f3n Internacional","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/91b9e676dca8842a983b89793a34e5b8"},"headline":"&#8220;Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa&#8221; &#8211; Anto\u00f1ita Day","datePublished":"2025-04-26T23:00:00+00:00","dateModified":"2025-04-26T23:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/"},"wordCount":999,"publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2025\/04\/CartasSup.G.-Portada-18.png","keywords":["Anto\u00f1ita"],"articleSection":["FASFI","fi","Hijas de Jes\u00fas","Juventude","Liturgia &#8211; oraci\u00f3n","Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/","url":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/","name":"\"Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa\" - Anto\u00f1ita Day - Hijas de Jes\u00fas","isPartOf":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/#primaryimage"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/#primaryimage"},"thumbnailUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2025\/04\/CartasSup.G.-Portada-18.png","datePublished":"2025-04-26T23:00:00+00:00","dateModified":"2025-04-26T23:00:23+00:00","description":"A festa de Anto\u00f1ita, neste ano de 2025, est\u00e1 entrela\u00e7ada com outras celebra\u00e7\u00f5es e eventos. Somos convidados a dar uma olhada mais de perto no \"entrela\u00e7amento desses fios\" e em seu significado para nossas vidas.","breadcrumb":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/#primaryimage","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2025\/04\/CartasSup.G.-Portada-18.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2025\/04\/CartasSup.G.-Portada-18.png","width":2185,"height":1550},{"@type":"BreadcrumbList","@id":"https:\/\/hijasdejesus.org\/pt-br\/seguir-jesus-e-estar-ao-lado-dos-pobres-e-a-mesma-coisa-antonita-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hijasdejesus.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"&#8220;Seguir Jesus e estar ao lado dos pobres \u00e9 a mesma coisa&#8221; &#8211; Anto\u00f1ita Day"}]},{"@type":"WebSite","@id":"https:\/\/hijasdejesus.org\/pt-br\/#website","url":"https:\/\/hijasdejesus.org\/pt-br\/","name":"Hijas de Jes\u00fas","description":"Despertamos a Jes\u00fas en el coraz\u00f3n, sacando lo mejor de las personas. Somos una congregaci\u00f3n religiosa ignaciana fundada por la Madre Candida","publisher":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hijasdejesus.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/hijasdejesus.org\/pt-br\/#organization","name":"Hijas de Jes\u00fas","url":"https:\/\/hijasdejesus.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","contentUrl":"https:\/\/hijasdejesus.org\/wp-content\/uploads\/2023\/01\/Hijas-de-Jesus_hor-A7C957.png","width":700,"height":360,"caption":"Hijas de Jes\u00fas"},"image":{"@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hijasdejesusenelmundo\/","https:\/\/x.com\/hijasdjesus"]},{"@type":"Person","@id":"https:\/\/hijasdejesus.org\/pt-br\/#\/schema\/person\/91b9e676dca8842a983b89793a34e5b8","name":"Comunicaci\u00f3n Internacional","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/dcb9b61797c934872aa9209ebf48b92edfeb0819dcdcaa77cd84879d6def414d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dcb9b61797c934872aa9209ebf48b92edfeb0819dcdcaa77cd84879d6def414d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dcb9b61797c934872aa9209ebf48b92edfeb0819dcdcaa77cd84879d6def414d?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n Internacional"},"url":"https:\/\/hijasdejesus.org\/pt-br\/author\/comunicacion-internacional\/"}]}},"_links":{"self":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/48072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/comments?post=48072"}],"version-history":[{"count":1,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/48072\/revisions"}],"predecessor-version":[{"id":48074,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/posts\/48072\/revisions\/48074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media\/48056"}],"wp:attachment":[{"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/media?parent=48072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/categories?post=48072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hijasdejesus.org\/pt-br\/wp-json\/wp\/v2\/tags?post=48072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}